{"id":3888,"date":"2017-12-26T22:04:23","date_gmt":"2017-12-26T21:04:23","guid":{"rendered":"http:\/\/bwf-neu.zephir.digital\/?page_id=3888"},"modified":"2018-03-16T15:51:04","modified_gmt":"2018-03-16T14:51:04","slug":"action-photos","status":"publish","type":"page","link":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/","title":{"rendered":"Action Photos"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-1975374960\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1158689588\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"542\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-1024x544.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-1024x544.png 1024w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-500x266.png 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-600x319.png 600w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-800x425.png 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55-768x408.png 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.55.png 1498w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1158689588 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_570753424\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-1024x540.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-1024x540.png 1024w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-500x263.png 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-600x316.png 600w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-800x422.png 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26-768x405.png 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-29-um-12.14.26.png 1488w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_570753424 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_95627728\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"518\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147-500x324.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147-600x389.jpg 600w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147-768x497.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_95627728 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-245607266\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-245607266 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h1>Action Photos<\/h1>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_123.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_123.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_123.jpg 697w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_123-500x574.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_123-600x689.jpg 600w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_162.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_162.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_162.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_162-500x281.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_162-600x337.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.34.35.png\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"316\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.34.35.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.34.35.png 1200w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.34.35-500x263.png 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.34.35-600x315.png 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_161.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_161.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_159.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"371\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_159.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_159.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_159-500x309.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_159-600x371.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_158.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"409\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_158.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_158.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_158-500x341.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_158-600x409.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.33.57.png\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"322\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.33.57.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.33.57.png 1200w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.33.57-500x268.png 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/Bildschirmfoto-2017-12-28-um-21.33.57-600x322.png 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_156.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"453\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_156.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_156.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_156-500x378.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_156-600x453.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_155.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"441\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_155.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_155.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_155-500x368.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_155-600x441.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_048.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"428\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_048.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_048.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_048-500x356.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_048-600x428.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_006.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_006.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_006.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_006-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_006-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_154.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_154.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_154.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_154-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_154-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_153.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_153.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_153.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_153-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_153-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_152.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_152.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_152.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_152-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_152-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_151.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_151.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_151.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_151-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_151-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_150.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"384\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_150.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_150.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_150-500x320.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_150-600x384.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_148.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"389\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_148.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_148.jpg 518w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_148-500x772.jpg 500w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"389\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147-500x324.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_147-600x389.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_146.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"389\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_146.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_146.jpg 518w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_146-500x772.jpg 500w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_145.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"389\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_145.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_145.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_145-500x324.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_145-600x389.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_144.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_144.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_144.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_144-500x332.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_144-600x398.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_143.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_143.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_143.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_143-500x332.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_143-600x398.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_142.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_142.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_142.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_142-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_142-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_140.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_140.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_140.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_140-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_140-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_138.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_138.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_138.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_138-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_138-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_137.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_137.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_137.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_137-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_137-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_136.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"477\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_136.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_136.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_136-500x398.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_136-600x477.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_135.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_135.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_135.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_135-500x259.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_135-600x311.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_134.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"449\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_134.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_134.jpg 599w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_134-500x668.jpg 500w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_133.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"447\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_133.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_133.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_133-500x373.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_133-600x447.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_132.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_132.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_132.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_132-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_132-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_131.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"340\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_131.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_131.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_131-500x283.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_131-600x340.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_130.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_130.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_130.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_130-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_130-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_129.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_129.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_129.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_129-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_129-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_128.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"443\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_128.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_128.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_128-500x369.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_128-600x443.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_127.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"425\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_127.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_127.jpg 567w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_127-500x705.jpg 500w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_126.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"389\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_126.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_126.jpg 519w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_126-500x771.jpg 500w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_122.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"419\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_122.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_122.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_122-500x349.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_122-600x419.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_121.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"508\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_121.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_121.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_121-500x423.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_121-600x508.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_120.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_120.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_120.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_120-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_120-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_119.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"374\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_119.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_119.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_119-500x311.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_119-600x374.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_118.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"365\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_118.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_118.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_118-500x304.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_118-600x365.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_117.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_117.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_117.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_117-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_117-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_116.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"538\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_116.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_116.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_116-500x448.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_116-600x538.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_115.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"375\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_115.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_115.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_115-500x313.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_115-600x375.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_113.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"368\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_113.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_113.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_113-500x306.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_113-600x368.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_112.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"448\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_112.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_112.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_112-500x373.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_112-600x448.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_111.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_111.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_111.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_111-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_111-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_110.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_110.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_110.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_110-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_110-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_109.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"456\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_109.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_109.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_109-500x380.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_109-600x456.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_107.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_107.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_107.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_107-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_107-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_105.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_105.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_105.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_105-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_105-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_104.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_104.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_104.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_104-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_104-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_102.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"482\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_102.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_102.jpg 642w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_102-500x622.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_102-600x747.jpg 600w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_098.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"416\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_098.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_098.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_098-500x347.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_098-600x416.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_094.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"429\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_094.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_094.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_094-500x358.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_094-600x429.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_093.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_093.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_093.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_093-500x339.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_093-600x407.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_092.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"421\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_092.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_092.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_092-500x351.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_092-600x421.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_088.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_088.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_088.jpg 769w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_088-500x520.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_088-600x624.jpg 600w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_087.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_087.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_087.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_087-500x339.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_087-600x407.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_084.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"367\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_084.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_084.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_084-500x306.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_084-600x367.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_083.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"380\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_083.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_083.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_083-500x317.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_083-600x380.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_081.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"458\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_081.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_081.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_081-500x381.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_081-600x458.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_080.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"431\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_080.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_080.jpg 574w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_080-500x697.jpg 500w\" sizes=\"auto, (max-width: 431px) 100vw, 431px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_079.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"446\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_079.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_079.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_079-500x372.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_079-600x446.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_078.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"448\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_078.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_078.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_078-500x373.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_078-600x448.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_077.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_077.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_077.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_077-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_077-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_076.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_076.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_076.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_076-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_076-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_075.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_075.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_075.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_075-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_075-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_074.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"442\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_074.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_074.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_074-500x368.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_074-600x442.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_072.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"434\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_072.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_072.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_072-500x362.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_072-600x434.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_071.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_071.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_071.jpg 533w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_071-500x750.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_070.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"446\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_070.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_070.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_070-500x371.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_070-600x446.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_068.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_068.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_068.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_068-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_068-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_067.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"462\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_067.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_067.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_067-500x385.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_067-600x462.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_066.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"333\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_066.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_066.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_066-500x278.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_066-600x333.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_065.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_065.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_065.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_065-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_065-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_064.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"420\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_064.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_064.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_064-500x350.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_064-600x420.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_062.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"449\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_062.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_062.jpg 599w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_062-500x668.jpg 500w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_061.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"399\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_061.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_061.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_061-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_061-600x399.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_059.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"472\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_059.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_059.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_059-500x393.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_059-600x472.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_058.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"446\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_058.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_058.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_058-500x372.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_058-600x446.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_057.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"427\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_057.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_057.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_057-500x356.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_057-600x427.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_052.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_052.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_052.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_052-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_052-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_051.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_051.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_051.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_051-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_051-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_050.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_050.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_050.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_050-500x375.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_050-600x450.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_049.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"447\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_049.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_049.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_049-500x373.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_049-600x447.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_045.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_045.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_045.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_045-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_045-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_041.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_041.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_041.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_041-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_041-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_040.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_040.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_040.jpg 533w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_040-500x750.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_037.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_037.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_037.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_037-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_037-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_036.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_036.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_036.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_036-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_036-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_018.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_018.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_018.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_018-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_018-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_032.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_032.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_032.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_032-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_032-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_026.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_026.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_026.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_026-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_026-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_025.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_025.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_025.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_025-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_025-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_022.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_022.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_022.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_022-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_022-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_019.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_019.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_019.jpg 533w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_019-500x750.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_017.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_017.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_017.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_017-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_017-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_015.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"406\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_015.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_015.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_015-500x338.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_015-600x406.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_014.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_014.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_014.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_014-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_014-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_013.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_013.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_013.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_013-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_013-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_012.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_012.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_012.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_012-500x333.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_012-600x400.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_010.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"452\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_010.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_010.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_010-500x377.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_010-600x452.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_008.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"446\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_008.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_008.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_008-500x372.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_008-600x446.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_007.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"458\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_007.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_007.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_007-500x382.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_007-600x458.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_005.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"432\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_005.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_005.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_005-500x360.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_005-600x432.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_004.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"467\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_004.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"6650,6586,6808,6588,6590,6592,6810,6594,6596,6756,6800,6598,6600,6602,6604,6606,6608,6610,6612,6614,6616,6618,6620,6622,6624,6626,6628,6630,6632,6634,6636,6638,6640,6642,6644,6646,6648,6652,6654,6656,6658,6660,6662,6664,6666,6670,6672,6674,6676,6678,6680,6682,6684,6686,6688,6690,6692,6694,6696,6698,6700,6702,6704,6706,6708,6710,6712,6714,6716,6718,6720,6722,6724,6726,6728,6730,6732,6734,6736,6738,6740,6742,6744,6748,6750,6752,6754,6758,6762,6764,6766,6768,6782,6770,6774,6776,6778,6780,6784,6786,6788,6790,6792,6794,6796,6798,6802,6804\" style=\"normal\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_004.jpg 800w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_004-500x389.jpg 500w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2017\/12\/action_004-600x467.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Action Photos<\/p>\n","protected":false},"author":1575,"featured_media":14356,"parent":345,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-sub-nav-vertical.php","meta":{"footnotes":""},"class_list":["post-3888","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Action Photos - BluewaterFishing<\/title>\n<meta name=\"description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Action Photos - BluewaterFishing\" \/>\n<meta property=\"og:description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/\" \/>\n<meta property=\"og:site_name\" content=\"BluewaterFishing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BWF.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-16T14:51:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2018\/01\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/\",\"name\":\"Action Photos - BluewaterFishing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png\",\"datePublished\":\"2017-12-26T21:04:23+00:00\",\"dateModified\":\"2018-03-16T14:51:04+00:00\",\"description\":\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png\",\"contentUrl\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png\",\"width\":1024,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/action-photos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photos\",\"item\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Action Photos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/#website\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/\",\"name\":\"BluewaterFishing\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluewaterfishing.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Action Photos - BluewaterFishing","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/","og_locale":"en_US","og_type":"article","og_title":"Action Photos - BluewaterFishing","og_description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","og_url":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/","og_site_name":"BluewaterFishing","article_publisher":"https:\/\/www.facebook.com\/BWF.eu","article_modified_time":"2018-03-16T14:51:04+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2018\/01\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/","url":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/","name":"Action Photos - BluewaterFishing","isPartOf":{"@id":"https:\/\/bluewaterfishing.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/#primaryimage"},"image":{"@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/#primaryimage"},"thumbnailUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2018\/01\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png","datePublished":"2017-12-26T21:04:23+00:00","dateModified":"2018-03-16T14:51:04+00:00","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","breadcrumb":{"@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/#primaryimage","url":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2018\/01\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png","contentUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2018\/01\/Bildschirmfoto-2017-12-28-um-21.33.57-1024x549.png","width":1024,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/bluewaterfishing.eu\/en\/photos\/action-photos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bluewaterfishing.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Photos","item":"https:\/\/bluewaterfishing.eu\/en\/photos\/"},{"@type":"ListItem","position":3,"name":"Action Photos"}]},{"@type":"WebSite","@id":"https:\/\/bluewaterfishing.eu\/#website","url":"https:\/\/bluewaterfishing.eu\/","name":"BluewaterFishing","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluewaterfishing.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/3888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/users\/1575"}],"replies":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/comments?post=3888"}],"version-history":[{"count":4,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/3888\/revisions"}],"predecessor-version":[{"id":21463,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/3888\/revisions\/21463"}],"up":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media\/14356"}],"wp:attachment":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media?parent=3888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}