{"id":37997,"date":"2024-04-03T14:39:36","date_gmt":"2024-04-03T12:39:36","guid":{"rendered":"https:\/\/bluewaterfishing.eu\/?page_id=37997"},"modified":"2024-06-28T18:17:01","modified_gmt":"2024-06-28T16:17:01","slug":"seychellen-2024","status":"publish","type":"page","link":"https:\/\/bluewaterfishing.eu\/en\/travelogues\/seychelles\/seychellen-2024\/","title":{"rendered":"Seychelles 2024"},"content":{"rendered":"\n\t<section class=\"section dark\" id=\"section_1465442735\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"788\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1547331101\">\n\n\t<div id=\"col-988146493\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1465442735 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 400px;\n}\n#section_1465442735 .section-bg img {\n  object-position: 51% 0%;\n}\n@media (min-width:550px) {\n  #section_1465442735 {\n    min-height: 750px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_202756516\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1518879973\">\n\n\t<div id=\"col-478110049\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3114980443\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\">Providence ATOLL | Seychelles<\/h2>\n<p>February 2024<\/p>\n\t\t\n<style>\n#text-3114980443 {\n  line-height: 0.75;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-71567876\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-71567876 {\n  padding-top: 30px;\n}\n@media (min-width:550px) {\n  #gap-71567876 {\n    padding-top: 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<h3>Providence proved to be a fantastic fishing destination with all the impressive catches made throughout the week, proving to be a fantastic fishing destination, once again. Helmut Zaderer was finishing hosting his week with his guests, Kay Jones, Libby Alcorn, Stephan Kreupl, Rene Noth, and Vadim Titovets.<\/h3>\n<p>The first days of the week started with some winds and rain. However, this did not deter the team from landing some great catches.<\/p>\n<p>Kay and Libby aimed to land a bumphead parrotfish. Unfortunately, they hooked but lost some throughout the week. This did not diminish their dedication. On their final day, they managed to achieve their goal.<\/p>\n<p>No stranger to the flats of the Seychelles, Vadim also had a fantastic week. He landed several GTs, a moustache triggerfish, a milkfish, and a tremendous bumpy. His skiff partner Stephan had a stellar week, ending up with several geets, three bumpies, a milkfish, and three whopping yellowmargin triggerfish measuring 50, 53 cm and 55 cm. During the week, he achieved two flats slams, including a fantastic fight with a monstrous GT estimated at around 120 cm. Unfortunately, the sneaky fish darted for the corals and cut the leader. Nonetheless, it is a fight he will remember for a very long time.<\/p>\n<p>Rene had a solid week. He landed several GTs, his biggest measuring an epic 99 cm. He also hooked up several bumps and managed to net three.<\/p>\n<p>Helmut stole the spotlight once again this week. With many GTs, Helmut bagged his biggest at 95 cm, making his overall week measurement an incredible 105 cm. On one of his days, he landed two GTs, two yellowmargin triggerfish, and two bumphead parrotfish, achieving a double flats slam, a feat not often accomplished. His scorecard included eight GTs, four bumpies, five triggerfish, and one milkfish.<\/p>\n<p>Overall, as the weather calmed later in the week, it turned out to be an incredible week shared with great friends.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-478110049 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_202756516 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1387910908\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-720797460\">\n\n\t<div id=\"col-9633137\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div id=\"gallery-1835637732\" class=\"row large-columns-5 medium-columns-3 small-columns-2 row-small row-full-width row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4275.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4278.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"225\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1-400x225.webp\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1-400x225.webp 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1-1000x563.webp 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1-768x432.webp 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-aerial-panoramic-1024x576-1.webp 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3865.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"309\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender-309x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender-309x400.jpeg 309w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender-772x1000.jpeg 772w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender-768x995.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/FullSizeRender.jpeg 926w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4170.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"248\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4170-248x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4170-248x400.jpeg 248w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4170-619x1000.jpeg 619w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4170.jpeg 743w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0765.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0766.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0779.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-17-2.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4025.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3938.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3954.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921-294x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921-294x400.jpeg 294w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921-735x1000.jpeg 735w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921-768x1045.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3921.jpeg 882w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-5.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Cam-week-5-8.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\" title=\"DCIM100MEDIADJI_0012.JPG\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"263\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2-400x263.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2-400x263.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2-1000x657.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2-768x504.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>DCIM100MEDIADJI_0012.JPG<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0367.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0393.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-19-2.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1-400x267.webp\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1-400x267.webp 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1-1000x667.webp 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1-768x512.webp 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-03-scaled-1.webp 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232-288x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232-288x400.jpeg 288w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232-720x1000.jpeg 720w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232-768x1067.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0232.jpeg 864w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-2-5.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-22.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-7-5.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-23.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0432.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4015.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-27.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28-267x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28-267x400.jpg 267w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28-667x1000.jpg 667w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28-768x1152.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-28.jpg 800w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-33.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"303\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246-400x303.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246-400x303.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246-1000x758.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246-768x582.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0246.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251-1000x751.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251-768x577.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0251.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0760.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0777.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_0778.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3864.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3879-1.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3883.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3958.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-18-2.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3886.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3866.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3924.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3928.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-1-6.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3931.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3967.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3993.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3997.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3999.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"266\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1-400x266.webp\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1-400x266.webp 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1-1000x666.webp 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1-768x511.webp 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/seychelles-providence-atoll-scenic-04-scaled-1.webp 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005-749x1000.jpeg 749w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005-768x1025.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4005.jpeg 899w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4022.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-6-5-1.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4050.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3-400x267.jpg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3-1000x666.jpg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3-768x512.jpg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Graham-AFC-15-3.jpg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4092.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_3871.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4060.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4103.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4114.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4129.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4145.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4169.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1-1000x749.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1-768x575.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/455df2fe4faa2e9e3e83fb00e4432caf-1.jpeg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4176.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"294\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197-400x294.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197-400x294.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197-1000x735.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197-768x564.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4197.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4211.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220-260x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220-260x400.jpeg 260w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220-651x1000.jpeg 651w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220-768x1180.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4220.jpeg 781w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4270.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1478.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4300.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4300-223x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37769,37773,37784,37685,37615,37755,37669,37671,37679,37631,37733,37713,37715,37705,37609,37613,37786,37657,37661,37635,37788,37649,37619,37637,37625,37639,37663,37729,37643,37645,37647,37653,37655,37665,37675,37677,37683,37781,37699,37717,37633,37701,37687,37707,37709,37617,37711,37719,37721,37723,37725,37792,37727,37731,37777,37737,37627,37741,37691,37739,37743,37745,37747,37751,37753,37790,37757,37759,37761,37765,37767,37681,37775\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4300-223x400.jpeg 223w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4300-558x1000.jpeg 558w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4300.jpeg 669w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1387910908 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1862973735\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-531813643\">\n\n\t<div id=\"col-1354394111\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4218580693\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\">Alphonse ISLAND | SeychelleS<\/h2>\n<p>February 2024<\/p>\n\t\t\n<style>\n#text-4218580693 {\n  line-height: 0.75;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1844773942\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1844773942 {\n  padding-top: 30px;\n}\n@media (min-width:550px) {\n  #gap-1844773942 {\n    padding-top: 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<p><span class=\"Y2IQFc\" lang=\"en\">This year Helmut combined 2 destinations (Providence and Cosmoledo). For organizational reasons we visited Alphonse Island for 2 days in between.<\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1354394111 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1862973735 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1029228939\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-292022205\">\n\n\t<div id=\"col-1603396908\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div id=\"gallery-1082900918\" class=\"row large-columns-5 medium-columns-3 small-columns-2 row-small row-full-width row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4299.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"231\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4299-231x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4299-231x400.jpeg 231w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4299-578x1000.jpeg 578w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4299.jpeg 694w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4282.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4432.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4293.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4301.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"231\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4301-231x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4301-231x400.jpeg 231w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4301-578x1000.jpeg 578w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4301.jpeg 693w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4287.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4291.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4424.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4298.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4315.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4306.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4297.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4476.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"298\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387-298x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387-298x400.jpeg 298w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387-745x1000.jpeg 745w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387-768x1031.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4387.jpeg 894w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4388.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4388-251x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4388-251x400.jpeg 251w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4388-628x1000.jpeg 628w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4388.jpeg 753w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4406.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4442.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4302.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"228\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4302-228x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4302-228x400.jpeg 228w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4302-569x1000.jpeg 569w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4302.jpeg 683w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4318.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4307.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4451.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4402.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4458.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4389.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"238\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4389-238x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4389-238x400.jpeg 238w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4389-596x1000.jpeg 596w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4389.jpeg 715w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4498.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4395.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4411.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"261\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500-400x261.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500-400x261.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500-1000x654.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500-768x502.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4500.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4491.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4482.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"220\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501-400x220.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501-400x220.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501-1000x551.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501-768x423.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4501.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4487.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4431.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"282\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415-282x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37815,37801,37849,37809,37817,37803,37807,37845,37813,37825,37821,37811,37857,37829,37831,37839,37851,37819,37827,37823,37853,37837,37855,37833,37865,37835,37841,37867,37863,37859,37869,37861,37847,37843\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415-282x400.jpeg 282w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415-704x1000.jpeg 704w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415-768x1091.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4415.jpeg 845w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1029228939 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1616241230\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1786337325\">\n\n\t<div id=\"col-824578995\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3532957590\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\">Cosmoledo ATOLL | SeychelleS<\/h2>\n<p>February 2024<\/p>\n\t\t\n<style>\n#text-3532957590 {\n  line-height: 0.75;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1928036892\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1928036892 {\n  padding-top: 30px;\n}\n@media (min-width:550px) {\n  #gap-1928036892 {\n    padding-top: 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<p>This week got off to a bit of a bumpy start in Cosmoledo due to the bad weather. Nevertheless, numerous fish were caught. Helmut had a phenomenal week of fishing. He managed to catch two big Giant trevally of 121 cm and a 125 cm. Congratulations to Helmut. Overall, we had a very successful week on Cosmoledo with a good number of fish caught.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-824578995 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1616241230 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1848264344\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-344508986\">\n\n\t<div id=\"col-699110202\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div id=\"gallery-1514043879\" class=\"row large-columns-5 medium-columns-3 small-columns-2 row-small row-full-width row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4510.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4632.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4629.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2090.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4662.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4563.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4567.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1939.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4574.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1960.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4646.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4576.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4607.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1954.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4664.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4600.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4605.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4514.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2017.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4568.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1972.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"385\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626-400x385.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626-400x385.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626-1000x964.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626-768x740.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4626.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980-270x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980-270x400.jpeg 270w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980-676x1000.jpeg 676w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980-768x1136.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_1980.jpeg 811w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2015.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2049.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577-1000x749.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577-768x575.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4577.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4516.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4562.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"261\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692-400x261.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692-400x261.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692-1000x654.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692-768x502.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4692.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4566.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4575.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4631.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4633.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4635.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4660.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_2105.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4670.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4673.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4677.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4687.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4689.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.39.46-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.39.46-1-236x400.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.39.46-1-236x400.png 236w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.39.46-1-590x1000.png 590w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.39.46-1.png 708w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4821.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4784-2.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4815.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4798.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4834.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/IMG_4804.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"361\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57-400x361.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"37899,37939,37935,37895,37949,37909,37915,37877,37919,37883,37945,37923,37931,37881,37951,37927,37929,37903,37891,37917,37885,37933,37887,37889,37893,37925,37905,37907,37963,37913,37921,37937,37941,37943,37947,37897,37953,37955,37957,37959,37961,37988,37983,37971,37981,37977,37985,37979,37873\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"5\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57-400x361.png 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57-1000x902.png 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57-768x693.png 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/Bildschirmfoto-2024-02-29-um-15.38.57.png 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1848264344 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1575,"featured_media":37786,"parent":17475,"menu_order":83,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-37997","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seychelles 2024 - BluewaterFishing<\/title>\n<meta name=\"description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seychelles 2024 - BluewaterFishing\" \/>\n<meta property=\"og:description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"BluewaterFishing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BWF.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T16:17:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/\",\"url\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/\",\"name\":\"Seychelles 2024 - BluewaterFishing\",\"isPartOf\":{\"@id\":\"https:\/\/bluewaterfishing.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\",\"datePublished\":\"2024-04-03T12:39:36+00:00\",\"dateModified\":\"2024-06-28T16:17:01+00:00\",\"description\":\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\",\"breadcrumb\":{\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage\",\"url\":\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\",\"contentUrl\":\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg\",\"width\":1200,\"height\":788,\"caption\":\"DCIM100MEDIADJI_0012.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/bluewaterfishing.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travelogues\",\"item\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seychelles\",\"item\":\"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Seychelles 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bluewaterfishing.eu\/#website\",\"url\":\"https:\/\/bluewaterfishing.eu\/\",\"name\":\"BluewaterFishing\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bluewaterfishing.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seychelles 2024 - BluewaterFishing","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/","og_locale":"en_US","og_type":"article","og_title":"Seychelles 2024 - BluewaterFishing","og_description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","og_url":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/","og_site_name":"BluewaterFishing","article_publisher":"https:\/\/www.facebook.com\/BWF.eu","article_modified_time":"2024-06-28T16:17:01+00:00","og_image":[{"width":1200,"height":788,"url":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/","url":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/","name":"Seychelles 2024 - BluewaterFishing","isPartOf":{"@id":"https:\/\/bluewaterfishing.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage"},"image":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg","datePublished":"2024-04-03T12:39:36+00:00","dateModified":"2024-06-28T16:17:01+00:00","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","breadcrumb":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#primaryimage","url":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg","contentUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2024\/04\/PM-Providence_-2.jpg","width":1200,"height":788,"caption":"DCIM100MEDIADJI_0012.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/seychellen-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bluewaterfishing.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Travelogues","item":"https:\/\/bluewaterfishing.eu\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Seychelles","item":"https:\/\/bluewaterfishing.eu\/reiseberichte\/seychellen\/"},{"@type":"ListItem","position":4,"name":"Seychelles 2024"}]},{"@type":"WebSite","@id":"https:\/\/bluewaterfishing.eu\/#website","url":"https:\/\/bluewaterfishing.eu\/","name":"BluewaterFishing","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluewaterfishing.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/37997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/users\/1575"}],"replies":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/comments?post=37997"}],"version-history":[{"count":3,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/37997\/revisions"}],"predecessor-version":[{"id":38042,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/37997\/revisions\/38042"}],"up":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/17475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media\/37786"}],"wp:attachment":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media?parent=37997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}