{"id":36340,"date":"2023-06-11T10:35:46","date_gmt":"2023-06-11T08:35:46","guid":{"rendered":"https:\/\/bluewaterfishing.eu\/?page_id=36340"},"modified":"2023-06-12T09:12:46","modified_gmt":"2023-06-12T07:12:46","slug":"malediven-2023","status":"publish","type":"page","link":"https:\/\/bluewaterfishing.eu\/en\/travelogues\/maldives\/malediven-2023\/","title":{"rendered":"Malediven 2023"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-1028199627\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1100513847\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7453-1000x750.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7453-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7453-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7453-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7453.jpeg 1100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1100513847 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_632563715\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7810-1000x750.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7810-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7810-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7810-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7810.jpeg 1100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_632563715 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2112082933\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:400px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-1000x750.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439.jpeg 1100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2112082933 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-2007145\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2007145 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div id=\"c5142\" class=\"csc-default\">\n<h1>Maldives Photo Album January 2023<\/h1>\n<\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1438523416\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 30px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7623-1000x750.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7623-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7623-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7623-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7623.jpeg 1100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1438523416 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129-1000x825.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"330\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129-400x330.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129-400x330.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129-1000x825.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129-768x634.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8129.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7582.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7206.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7868.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-1000x749.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-1000x749.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-768x575.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8243.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36305,36265,36299,36319,36291,36271,36283,36307\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7164.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1301194609\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 30px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8224-1000x750.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8224-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8224-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8224-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8224.jpeg 1100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1301194609 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8218.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156-1000x768.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"307\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156-400x307.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156-400x307.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156-1000x768.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156-768x590.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8156.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8361.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429-1000x666.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429-400x267.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429-400x267.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429-1000x666.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429-768x512.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7429.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314-1000x614.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"245\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314-400x245.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314-400x245.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314-1000x614.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314-768x471.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7314.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8246.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8386.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36275,36295,36251,36311,36287,36269,36249,36289\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7245.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1865025907\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 30px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8424-750x1000.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8424-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8424-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8424-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8424.jpeg 900w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1865025907 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7589.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605-1000x751.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605-1000x751.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605-768x577.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7605.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437-750x1000.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437-300x400.jpeg 300w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437-750x1000.jpeg 750w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437-768x1024.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8437.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8438.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8427.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209-1000x745.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"298\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209-400x298.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209-400x298.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209-1000x745.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209-768x572.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8209.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8190.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196-1000x749.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196-1000x749.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196-768x575.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8196.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8439.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-1000x749.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-1000x749.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238-768x575.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7238.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_8192.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166-1000x750.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image image-cover\" style=\"padding-top:150px;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"36263,36259,36243,36241,36245,36279,36285,36281,36239,36291,36283,36247\" style=\"default\" col_spacing=\"xsmall\" image_height=\"150px\" srcset=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166-400x300.jpeg 400w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166-1000x750.jpeg 1000w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166-768x576.jpeg 768w, https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7166.jpeg 1100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<p>Stephan Kreupl im Januar 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maldives Photo Album January 2023 Stephan Kreupl im Januar 2023<\/p>\n","protected":false},"author":1575,"featured_media":36255,"parent":17465,"menu_order":92,"comment_status":"closed","ping_status":"closed","template":"page-blank-sub-nav-vertical.php","meta":{"footnotes":""},"class_list":["post-36340","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malediven 2023 - BluewaterFishing<\/title>\n<meta name=\"description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malediven 2023 - BluewaterFishing\" \/>\n<meta property=\"og:description\" content=\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"BluewaterFishing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BWF.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T07:12:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7627.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"825\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/\",\"name\":\"Malediven 2023 - BluewaterFishing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IMG_7627.jpeg\",\"datePublished\":\"2023-06-11T08:35:46+00:00\",\"dateModified\":\"2023-06-12T07:12:46+00:00\",\"description\":\"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IMG_7627.jpeg\",\"contentUrl\":\"https:\\\/\\\/bluewaterfishing.eu\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IMG_7627.jpeg\",\"width\":1100,\"height\":825},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/malediven-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bluewaterfishing.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travelogues\",\"item\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maldives\",\"item\":\"https:\\\/\\\/bluewaterfishing.eu\\\/reiseberichte\\\/malediven\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Malediven 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluewaterfishing.eu\\\/#website\",\"url\":\"https:\\\/\\\/bluewaterfishing.eu\\\/\",\"name\":\"BluewaterFishing\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluewaterfishing.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malediven 2023 - BluewaterFishing","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/","og_locale":"en_US","og_type":"article","og_title":"Malediven 2023 - BluewaterFishing","og_description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","og_url":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/","og_site_name":"BluewaterFishing","article_publisher":"https:\/\/www.facebook.com\/BWF.eu","article_modified_time":"2023-06-12T07:12:46+00:00","og_image":[{"width":1100,"height":825,"url":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7627.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/","url":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/","name":"Malediven 2023 - BluewaterFishing","isPartOf":{"@id":"https:\/\/bluewaterfishing.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/#primaryimage"},"image":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7627.jpeg","datePublished":"2023-06-11T08:35:46+00:00","dateModified":"2023-06-12T07:12:46+00:00","description":"Visit our Travelogues, Videos and Catch-Reports and find your perfect lure for the fish of your dreams.","breadcrumb":{"@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/#primaryimage","url":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7627.jpeg","contentUrl":"https:\/\/bluewaterfishing.eu\/wp-content\/uploads\/2023\/06\/IMG_7627.jpeg","width":1100,"height":825},{"@type":"BreadcrumbList","@id":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/malediven-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bluewaterfishing.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Travelogues","item":"https:\/\/bluewaterfishing.eu\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Maldives","item":"https:\/\/bluewaterfishing.eu\/reiseberichte\/malediven\/"},{"@type":"ListItem","position":4,"name":"Malediven 2023"}]},{"@type":"WebSite","@id":"https:\/\/bluewaterfishing.eu\/#website","url":"https:\/\/bluewaterfishing.eu\/","name":"BluewaterFishing","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluewaterfishing.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/36340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/users\/1575"}],"replies":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/comments?post=36340"}],"version-history":[{"count":3,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/36340\/revisions"}],"predecessor-version":[{"id":36368,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/36340\/revisions\/36368"}],"up":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/pages\/17465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media\/36255"}],"wp:attachment":[{"href":"https:\/\/bluewaterfishing.eu\/en\/wp-json\/wp\/v2\/media?parent=36340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}